{"id":22217,"date":"2018-05-23T11:43:05","date_gmt":"2018-05-23T09:43:05","guid":{"rendered":"http:\/\/it.intoo.com\/?p=22217"},"modified":"2024-10-16T13:14:17","modified_gmt":"2024-10-16T13:14:17","slug":"cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente","status":"publish","type":"post","link":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/","title":{"rendered":"CV e Profilo Linkedin. Suggerimenti per una proposizione coerente"},"content":{"rendered":"<p style=\"text-align: right\">\/di Maril\u00f9 Anaclerio<\/p>\n<p>Versione classica del\u00a0<strong>CV e Profilo Linkedin<\/strong>. Essi non sono sempre due metodi alternativi di offrire la propria candidatura, ma spesso sono due strumenti complementari che viaggiano sinergicamente nella proposizione al mercato. Per questo motivo, se si vuole risultare credibili agli occhi di chi seleziona, \u00e8 fondamentale che i reciproci contenuti siano coerenti l\u2019uno con l\u2019altro e rispondano ad alcune <strong>regole prioritarie.<\/strong><\/p>\n<p>Se \u00e8 vero che la <em>digital proposition <\/em>sta diventando sempre pi\u00f9 importante e necessaria per non rimanere \u201cinvisibili\u201d agli occhi delle aziende o di chi assume in senso lato, dall\u2019altro \u00e8 altrettanto vero che la versione classica del CV (che per lo pi\u00f9 viaggia come documento allegato di una mail o, sempre pi\u00f9 raramente, in formato cartaceo) \u00e8 ancora uno strumento molto utilizzato sia per la sua capacit\u00e0 di raccontare in modo pi\u00f9 articolato le proprie esperienze, sia perch\u00e9 consente maggiormente di \u201ccustomizzare\u201d i contenuti rispetto ai singoli obiettivi e destinatari, evidenziando punti di contatto e sinergie.<\/p>\n<p>Alla luce di questa sempre pi\u00f9 necessaria complementariet\u00e0, diventa imprescindibile per chi si propone contemporaneamente nelle due forme (azione che consente sicuramente una maggiore efficacia nella presentazione di s\u00e8, dando la possibilit\u00e0 di coprire con maggiore capillarit\u00e0 le opportunit\u00e0 che il mercato offre, sia in attivo come propositori della propria candidatura, sia in passivo come riceventi manifestazioni d\u2019interesse) usare alcune accortezze.<\/p>\n<p>La prima \u00e8 sicuramente quella di prestare attenzione alla <strong>coerenza dei contenuti<\/strong> e alla <strong>veridicit\u00e0 di quanto si scrive<\/strong>. Partendo dal presupposto che quanto dichiarato in un cv debba sempre corrispondere a verit\u00e0, tale assunto \u00e8 ancor di pi\u00f9 basilare nel momento in cui la storia professionale del candidato\/a viaggia on line e si rende visibile a tutti. Questa \u201cbacheca\u201d universale, se da un lato comporta la maggiore possibilit\u00e0- in caso di immissioni di dati non veritieri &#8211; di essere smentiti da chi ci conosce bene, dall\u2019altro permette a tutti di far emergere il proprio potenziale e di poter incidere con pi\u00f9 efficacia nelle dinamiche di selezione.<\/p>\n<p>La coerenza tra i contenuti <em>off line<\/em> e quelli <em>on line<\/em> \u00e8 ovviamente altrettanto funzionale al fatto che si voglia risultare sinceri in quanto si dichiara. E\u2019 fin troppo chiaro che, laddove il recruiter dovesse ricevere da un candidato il suo cv in versione classica e questo dovesse essere difforme da quanto pubblicato sul suo profilo Linkedin, egli reputer\u00e0 \u2013 nella peggiore delle ipotesi \u2013 la sua candidatura non idonea o partir\u00e0 nella valutazione gi\u00e0 con degli elementi di dubbio che, giocoforza, lo influenzeranno nella fotografia complessiva che far\u00e0 della persona.<\/p>\n<p>Ci\u00f2 che non significa che il profilo social non potr\u00e0 essere pi\u00f9 sintetico di un cv \u201cclassico\u201d nell\u2019esposizione dei contenuti. Anzi per sua natura \u00e8 richiesto che lo sia, dal momento che proprio il suo essere <strong>smart<\/strong> lo rende maggiormente fruibile, facilitando una consultazione universalmente immediata. Laddove il concetto di sintesi abbia, per\u00f2, l\u2019accezione di compressione di concetti e non di loro omissione o \u201ctrasfigurazione\u201d al fine di risultare maggiormente appealing sul mercato.<\/p>\n<p>Va anche detto che, se da un lato Linkedin consente una penetrazione quasi completa dei canali di accesso al mercato, sia lato domanda che lato offerta, dall\u2019altro pu\u00f2 presentare delle caratteristiche di staticit\u00e0 che potrebbero andare a discapito di una proposizione mirata in cui di volta in volta evidenziare il fil rouge che lega lo scrivente al ricevente. A risolvere questo \u201cstallo\u201d ci pensa la famosa<strong> lettera di accompagnamento<\/strong>, sia essa il corpo di una mail o un messaggio Linkedin. E\u2019, infatti, in questo spazio che il candidato pu\u00f2 <strong>fare la differenza,<\/strong> mostrando il suo <strong>valore aggiunto<\/strong> ed ovviando ad un profilo social che, proponendosi come fotografia professionale, non pu\u00f2 essere valorizzato ogni volta in funzione del destinatario.<\/p>\n<p>Il consiglio \u00e8, quindi, quello di accompagnare sempre l\u2019invio delle proposizioni <em>off<\/em> e <em>on line<\/em> con una breve sintesi professionale all\u2019interno di una lettera motivazionale nella quale si spiega che cosa spinge a proporsi a quella realt\u00e0\/posizione e quali sono gli elementi di matching tra il ruolo richiesto e le skills che si possono mettere a disposizione.<\/p>\n<p style=\"text-align: right\">Se desideri ricevere ulteriori suggerimenti <a href=\"https:\/\/www.intoo.com\/it\/per-le-persone\/career-coaching\/\" target=\"_blank\" rel=\"noopener\">Registrati Gratuitamente qui.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\/di Maril\u00f9 Anaclerio Versione classica del\u00a0CV e Profilo Linkedin. Essi non sono sempre due metodi alternativi di offrire la propria candidatura, ma spesso sono due strumenti complementari che viaggiano sinergicamente nella proposizione al mercato. Per questo motivo, se si vuole risultare credibili agli occhi di chi seleziona, \u00e8 fondamentale che i reciproci contenuti siano coerenti [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22218,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[14,36],"tags":[],"class_list":["post-22217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cat-blog","category-linkedin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CV e Profilo LinkedIn. Qualche suggerimento strategico.<\/title>\n<meta name=\"description\" content=\"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CV e Profilo LinkedIn. Qualche suggerimento strategico.\" \/>\n<meta property=\"og:description\" content=\"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOO Italia\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-23T09:43:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T13:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1349\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elizabethkirk1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"CV e Profilo LinkedIn. Qualche suggerimento strategico.\" \/>\n<meta name=\"twitter:description\" content=\"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elizabethkirk1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/\"},\"author\":{\"name\":\"elizabethkirk1\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/3f7dc3d02001b96dbcc78a3242b4b874\"},\"headline\":\"CV e Profilo Linkedin. Suggerimenti per una proposizione coerente\",\"datePublished\":\"2018-05-23T09:43:05+00:00\",\"dateModified\":\"2024-10-16T13:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/\"},\"wordCount\":688,\"image\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/05\\\/photo-1526554850534-7c78330d5f90.jpg\",\"articleSection\":[\"Blog\",\"Linkedin\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/\",\"name\":\"CV e Profilo LinkedIn. Qualche suggerimento strategico.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/05\\\/photo-1526554850534-7c78330d5f90.jpg\",\"datePublished\":\"2018-05-23T09:43:05+00:00\",\"dateModified\":\"2024-10-16T13:14:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/3f7dc3d02001b96dbcc78a3242b4b874\"},\"description\":\"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/05\\\/photo-1526554850534-7c78330d5f90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/05\\\/photo-1526554850534-7c78330d5f90.jpg\",\"width\":1349,\"height\":901,\"caption\":\"Linkedin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CV e Profilo Linkedin. Suggerimenti per una proposizione coerente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/\",\"name\":\"INTOO Italia\",\"description\":\"Leader nello Sviluppo dell\u2019employability e Transizione di Carriera in Italia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/3f7dc3d02001b96dbcc78a3242b4b874\",\"name\":\"elizabethkirk1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g\",\"caption\":\"elizabethkirk1\"},\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/author\\\/elizabethkirk1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CV e Profilo LinkedIn. Qualche suggerimento strategico.","description":"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/","og_locale":"it_IT","og_type":"article","og_title":"CV e Profilo LinkedIn. Qualche suggerimento strategico.","og_description":"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!","og_url":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/","og_site_name":"INTOO Italia","article_published_time":"2018-05-23T09:43:05+00:00","article_modified_time":"2024-10-16T13:14:17+00:00","og_image":[{"width":1349,"height":901,"url":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","type":"image\/jpeg"}],"author":"elizabethkirk1","twitter_card":"summary_large_image","twitter_title":"CV e Profilo LinkedIn. Qualche suggerimento strategico.","twitter_description":"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!","twitter_image":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","twitter_misc":{"Written by":"elizabethkirk1","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#article","isPartOf":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/"},"author":{"name":"elizabethkirk1","@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/3f7dc3d02001b96dbcc78a3242b4b874"},"headline":"CV e Profilo Linkedin. Suggerimenti per una proposizione coerente","datePublished":"2018-05-23T09:43:05+00:00","dateModified":"2024-10-16T13:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/"},"wordCount":688,"image":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","articleSection":["Blog","Linkedin"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/","url":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/","name":"CV e Profilo LinkedIn. Qualche suggerimento strategico.","isPartOf":{"@id":"https:\/\/www.intoo.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#primaryimage"},"image":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","datePublished":"2018-05-23T09:43:05+00:00","dateModified":"2024-10-16T13:14:17+00:00","author":{"@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/3f7dc3d02001b96dbcc78a3242b4b874"},"description":"Scopri come integrare CV e LinkedIn per una candidatura efficace. Segui i consigli per mantenere coerenza e massimizzare le opportunit\u00e0!","breadcrumb":{"@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#primaryimage","url":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","contentUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2018\/05\/photo-1526554850534-7c78330d5f90.jpg","width":1349,"height":901,"caption":"Linkedin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoo.com\/it\/cv-e-profilo-linkedin-suggerimenti-per-una-proposizione-coerente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoo.com\/it\/"},{"@type":"ListItem","position":2,"name":"CV e Profilo Linkedin. Suggerimenti per una proposizione coerente"}]},{"@type":"WebSite","@id":"https:\/\/www.intoo.com\/it\/#website","url":"https:\/\/www.intoo.com\/it\/","name":"INTOO Italia","description":"Leader nello Sviluppo dell\u2019employability e Transizione di Carriera in Italia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/3f7dc3d02001b96dbcc78a3242b4b874","name":"elizabethkirk1","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fe0f44a6a3eb5244e1a9d785855bd2ce8965435a1f68b41adec0684bcc288df?s=96&d=mm&r=g","caption":"elizabethkirk1"},"url":"https:\/\/www.intoo.com\/it\/author\/elizabethkirk1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/22217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/comments?post=22217"}],"version-history":[{"count":2,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/22217\/revisions"}],"predecessor-version":[{"id":54558,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/22217\/revisions\/54558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/media\/22218"}],"wp:attachment":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/media?parent=22217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/categories?post=22217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/tags?post=22217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}