{"id":55755,"date":"2025-05-29T08:20:18","date_gmt":"2025-05-29T08:20:18","guid":{"rendered":"https:\/\/www.intoo.com\/it\/?p=55755"},"modified":"2025-05-29T09:09:23","modified_gmt":"2025-05-29T09:09:23","slug":"piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita","status":"publish","type":"post","link":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/","title":{"rendered":"Pi\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\u00e0"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>A inizio 2025 nel nostro Paese c\u2019erano <strong>quasi 10 milioni di lavoratori over50<\/strong>, il doppio rispetto a 20 anni prima, dato in parte legato alla stretta sull\u2019accesso alla pensione, ma soprattutto alle tendenze demografiche. Solo il <strong>20%<\/strong> dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.<\/p>\n<p><strong>Alessandra Giordano<\/strong>, direttrice Employability e Career Development di INTOO, spiega che \u201c<em>affrontare la longevit\u00e0 in modo strategico significa creare le condizioni affinch\u00e9 le competenze possano essere trattenute, trasferite e fatte evolvere<\/em>\u201d. Lo studio evidenzia infatti che non bastano solo incentivi al prepensionamento, ma servono piani strutturati: bisogna superare le discriminazioni dovute all\u2019et\u00e0, ma occorre anche lavorare sulla tecnologia e sulla formazione.<\/p>\n<p><strong>Leggi di seguito l\u2019articolo completo de Il Sole 24 Ore.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n\n    <div class='wp-block-pdfp-pdf-poster  alignnone' id='block-2'\n        data-attributes='{&quot;uniqueId&quot;:&quot;pdf-poster1&quot;,&quot;file&quot;:&quot;https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/05\\\/2025-05-28-Il_Sole_24_Ore.pdf&quot;,&quot;title&quot;:&quot;Pi\\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\\u00e0&quot;,&quot;height&quot;:{&quot;desktop&quot;:&quot;842px&quot;,&quot;tablet&quot;:&quot;700px&quot;,&quot;mobile&quot;:&quot;400px&quot;},&quot;width&quot;:{&quot;desktop&quot;:&quot;100%&quot;,&quot;tablet&quot;:&quot;100%&quot;,&quot;mobile&quot;:&quot;100%&quot;},&quot;print&quot;:false,&quot;showName&quot;:true,&quot;downloadButton&quot;:true,&quot;downloadButtonText&quot;:&quot;Download File&quot;,&quot;fullscreenButton&quot;:&quot;1&quot;,&quot;fullscreenButtonText&quot;:&quot;View Fullscreen&quot;,&quot;newWindow&quot;:false,&quot;actionsPosition&quot;:&quot;top&quot;,&quot;protect&quot;:false,&quot;keyboardNav&quot;:false,&quot;rtlMode&quot;:&quot;off&quot;,&quot;themeMode&quot;:&quot;light&quot;,&quot;annotationMode&quot;:true,&quot;openLinksInNewTab&quot;:false,&quot;progressiveLoading&quot;:true,&quot;defaultBrowser&quot;:false,&quot;adobeEmbedder&quot;:&quot;default&quot;,&quot;flipbookSourceType&quot;:&quot;pdf&quot;,&quot;flipbookSound&quot;:true,&quot;flipbookImages&quot;:[],&quot;btnStyles&quot;:{&quot;background&quot;:&quot;#1e73be&quot;,&quot;color&quot;:&quot;#ffffff&quot;,&quot;fontSize&quot;:&quot;1rem&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:20}},&quot;socialShare&quot;:{&quot;enabled&quot;:false,&quot;facebook&quot;:true,&quot;twitter&quot;:true,&quot;linkedin&quot;:true,&quot;pinterest&quot;:true,&quot;mailto&quot;:true,&quot;position&quot;:&quot;top&quot;},&quot;align&quot;:&quot;none&quot;,&quot;alignment&quot;:&quot;left&quot;,&quot;titleFontSize&quot;:&quot;16px&quot;,&quot;onlyPDF&quot;:false,&quot;thumbMenu&quot;:false,&quot;sidebarOpen&quot;:false,&quot;initialPage&quot;:0,&quot;alert&quot;:false,&quot;lastVersion&quot;:false,&quot;hrScroll&quot;:false,&quot;isHideRightToolbar&quot;:false,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:&quot;&quot;},&quot;adobeOptions&quot;:{&quot;showDownloadPDF&quot;:true,&quot;showPrintPDF&quot;:true,&quot;showAnnotationTools&quot;:true,&quot;showFullScreen&quot;:false,&quot;embedMode&quot;:&quot;SIZED_CONTAINER&quot;},&quot;popupOptions&quot;:{&quot;enabled&quot;:false,&quot;triggerType&quot;:&quot;button&quot;,&quot;image&quot;:&quot;&quot;,&quot;imagePdfIcon&quot;:true,&quot;imageHeight&quot;:&quot;200px&quot;,&quot;imageWidth&quot;:&quot;300px&quot;,&quot;text&quot;:&quot;Open PDF&quot;,&quot;btnStyle&quot;:{&quot;background&quot;:&quot;#2271b1&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;fontSize&quot;:&quot;16px&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}}},&quot;popupBtnStyle&quot;:{&quot;background&quot;:&quot;#2271b1&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}},&quot;popupBtnText&quot;:&quot;Open Document&quot;,&quot;CSS&quot;:&quot;&quot;,&quot;isPremium&quot;:false}'\n                data-pdfp-theme='light'        style=\"text-align: left\">\n                    <div class=\"pdfp_loading_placeholder\"\n                style=\"height: 842px; width: 100%; display: flex; align-items: center; justify-content: center; background: #f5f5f5; border: 1px solid #ddd;\">\n                <p>Loading Viewer...<\/p>\n            <\/div>\n            <\/div>\n\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A inizio 2025 nel nostro Paese c\u2019erano quasi 10 milioni di lavoratori over50, il doppio rispetto a 20 anni prima, dato in parte legato alla stretta sull\u2019accesso alla pensione, ma soprattutto alle tendenze demografiche. Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani. Alessandra [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":51853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"\n<h2>Chi vince nella classifica dell\u2019employability<\/h2>\nLa fascia d\u2019et\u00e0 tra i <strong>30-35<\/strong> e i<strong> 45 anni<\/strong> \u00e8 la pi\u00f9 appetibile per il mercato del lavoro odierno e, infatti, si sta dimostrando la pi\u00f9 dinamica.\n\nSono profili non pi\u00f9 junior, hanno gi\u00e0 una certa esperienza alle spalle, ma conservano quella curiosit\u00e0, quella freschezza, quel desiderio di crescita in grado di portare grande valore aggiunto. In pi\u00f9, dimostrano generalmente familiarit\u00e0 con gli strumenti e i processi tipici dell\u2019evoluzione digitale e non hanno ancora raggiunto l\u2019apice della potenzialit\u00e0 retributiva. Sintetizzano nel proprio profilo, insomma, una serie di caratteristiche che li rendono <strong>pi\u00f9 employable<\/strong> di altri.\n<h2>Come attrarre e mantenere i talenti<\/h2>\nRovescio della medaglia: sono i pi\u00f9 complessi da mantenere ingaggiati.\n\nSanno di \u201caver mercato\u201d e hanno aspettative alte che non sono disposti a negoziare; non lavorano solo per mantenersi, portano nel lavoro un desiderio di realizzazione multisfaccetata che comprende, ad esempio, il <strong>giusto equilibrio<\/strong> che li abilita a vivere un\u2019esistenza piena su pi\u00f9 fronti: il tempo della formazione, il tempo del benessere, il tempo delle relazioni, il tempo per godere della bellezza.\n\nE poi guardano ai <strong>valori<\/strong>, li pesano e decidono in base ad essi. Il <a href=\"https:\/\/www.intoo.com\/it\/cat-blog\/il-senso-del-lavoro-come-volano-per-la-produttivita\/\"><strong>sistema valoriale<\/strong><\/a> della propria azienda ha \u2013 per questa fascia d\u2019et\u00e0 \u2013 un peso ben pi\u00f9 alto che in passato. E questo \u00e8 dimostrato dalla gran massa di dimissionari che ha indicato come ragione principe della propria decisione la non corrispondenza valoriale. \u00c8 un punto centrale per le aziende, che dev\u2019essere compreso nella sua portata, in particolare da chi si occupa delle risorse umane, perch\u00e9 ha un potere anche d\u2019attrazione notevole.\n<h2>Le societ\u00e0 valoriali valgono di pi\u00f9<\/h2>\n\u00c8, insomma, una rivoluzione silenziosa che \u00e8 partita dai giovani adulti e si \u00e8 allargata, coinvolgendo la societ\u00e0 tout-court. Tanto che \u2013 sono dati pubblicati dal <strong>Sole24 Ore<\/strong> \u2013 i brand guidati da valori solidi crescono del 10% in pi\u00f9 all\u2019anno, dimostrando con i fatti e mettendo in mostra come aspetto prioritario delle loro scelte commerciali e strategiche valori etici, sostenibili solidali.\n\nEcco, dunque, che la sfera \u201csoft\u201d si fa \u201chard\u201d, l\u2019intangibile si fa tangibile traducendosi in numeri e riscontri che premiano chi sa mettere i valori al centro, con investimenti e direzioni chiare e consistenti, solide nel tempo.\n\nSet valoriali e performace sono interconnessi, laddove la forza del brand \u00e8 legata a doppio filo al suo significato: non pi\u00f9 un semplice logo, ma l\u2019essenza del suo purpose per attrarre talenti e acquisire nuove quote di mercato.\n<h3 style=\"text-align: center\">Dai nuova vita alla tua carriera: ricevi consigli e tecniche per affrontare il mercato del lavoro<\/h3>\n","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[445],"tags":[488],"class_list":["post-55755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rassegna-stampa","tag-il-sole-24-ore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione<\/title>\n<meta name=\"description\" content=\"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione\" \/>\n<meta property=\"og:description\" content=\"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOO Italia\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-29T08:20:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T09:09:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"305\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cesarescalabrino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cesarescalabrino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/\"},\"author\":{\"name\":\"cesarescalabrino\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/8792bd1596ec63eec4aa888f15648394\"},\"headline\":\"Pi\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\u00e0\",\"datePublished\":\"2025-05-29T08:20:18+00:00\",\"dateModified\":\"2025-05-29T09:09:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/\"},\"wordCount\":280,\"image\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/18-03-01-Ilsole24ore.com_Management.jpg\",\"keywords\":[\"il sole 24 ore\"],\"articleSection\":[\"Rassegna Stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/\",\"name\":\"Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/18-03-01-Ilsole24ore.com_Management.jpg\",\"datePublished\":\"2025-05-29T08:20:18+00:00\",\"dateModified\":\"2025-05-29T09:09:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/8792bd1596ec63eec4aa888f15648394\"},\"description\":\"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/18-03-01-Ilsole24ore.com_Management.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intoo.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/18-03-01-Ilsole24ore.com_Management.jpg\",\"width\":540,\"height\":305},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/\",\"name\":\"INTOO Italia\",\"description\":\"Leader nello Sviluppo dell\u2019employability e Transizione di Carriera in Italia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/#\\\/schema\\\/person\\\/8792bd1596ec63eec4aa888f15648394\",\"name\":\"cesarescalabrino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g\",\"caption\":\"cesarescalabrino\"},\"url\":\"https:\\\/\\\/www.intoo.com\\\/it\\\/author\\\/cesarescalabrino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione","description":"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/","og_locale":"it_IT","og_type":"article","og_title":"Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione","og_description":"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.","og_url":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/","og_site_name":"INTOO Italia","article_published_time":"2025-05-29T08:20:18+00:00","article_modified_time":"2025-05-29T09:09:23+00:00","og_image":[{"width":540,"height":305,"url":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","type":"image\/jpeg"}],"author":"cesarescalabrino","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","twitter_misc":{"Written by":"cesarescalabrino","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#article","isPartOf":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/"},"author":{"name":"cesarescalabrino","@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/8792bd1596ec63eec4aa888f15648394"},"headline":"Pi\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\u00e0","datePublished":"2025-05-29T08:20:18+00:00","dateModified":"2025-05-29T09:09:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/"},"wordCount":280,"image":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","keywords":["il sole 24 ore"],"articleSection":["Rassegna Stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/","url":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/","name":"Longevity: pi\u00f9 lavoratori over50 ma mancano piani di gestione","isPartOf":{"@id":"https:\/\/www.intoo.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#primaryimage"},"image":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","datePublished":"2025-05-29T08:20:18+00:00","dateModified":"2025-05-29T09:09:23+00:00","author":{"@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/8792bd1596ec63eec4aa888f15648394"},"description":"Solo il 20% dei lavoratori over50 dichiara per\u00f2 la presenza in azienda di politiche specifiche per i lavoratori pi\u00f9 anziani.","breadcrumb":{"@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#primaryimage","url":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","contentUrl":"https:\/\/www.intoo.com\/wp-content\/uploads\/sites\/3\/2023\/12\/18-03-01-Ilsole24ore.com_Management.jpg","width":540,"height":305},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoo.com\/it\/piu-lavoratori-over50-ma-mancano-piani-per-gestire-la-longevita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Pi\u00f9 lavoratori over50 ma mancano piani per gestire la longevit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.intoo.com\/it\/#website","url":"https:\/\/www.intoo.com\/it\/","name":"INTOO Italia","description":"Leader nello Sviluppo dell\u2019employability e Transizione di Carriera in Italia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoo.com\/it\/#\/schema\/person\/8792bd1596ec63eec4aa888f15648394","name":"cesarescalabrino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/020ee7034d311d1315c309450bbb5f6dfc96f720c494f7bcdb11dc0a2f79c0d5?s=96&d=mm&r=g","caption":"cesarescalabrino"},"url":"https:\/\/www.intoo.com\/it\/author\/cesarescalabrino\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/55755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/comments?post=55755"}],"version-history":[{"count":3,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/55755\/revisions"}],"predecessor-version":[{"id":55760,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/posts\/55755\/revisions\/55760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/media\/51853"}],"wp:attachment":[{"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/media?parent=55755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/categories?post=55755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoo.com\/it\/wp-json\/wp\/v2\/tags?post=55755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}